{"id":124,"count":0,"description":"","link":"https:\/\/thanhhaterracotta.com\/en\/magazine-publisher\/premier-publishing\/","name":"Premier Publishing","slug":"premier-publishing","taxonomy":"magazine-publisher","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v20.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Premier Publishing Archives - C\u00f4ng vi\u00ean - B\u1ea3o t\u00e0ng \u0110\u1ea5t nung Thanh H\u00e0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thanhhaterracotta.com\/en\/magazine-publisher\/premier-publishing\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premier Publishing Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thanhhaterracotta.com\/en\/magazine-publisher\/premier-publishing\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4ng vi\u00ean - B\u1ea3o t\u00e0ng \u0110\u1ea5t nung Thanh H\u00e0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/thanhhaterracotta.com\/magazine-publisher\/premier-publishing\/\",\"url\":\"https:\/\/thanhhaterracotta.com\/magazine-publisher\/premier-publishing\/\",\"name\":\"Premier Publishing Archives - C\u00f4ng vi\u00ean - B\u1ea3o t\u00e0ng \u0110\u1ea5t nung Thanh H\u00e0\",\"isPartOf\":{\"@id\":\"https:\/\/thanhhaterracotta.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/thanhhaterracotta.com\/magazine-publisher\/premier-publishing\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thanhhaterracotta.com\/magazine-publisher\/premier-publishing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Trang ch\u1ee7\",\"item\":\"https:\/\/thanhhaterracotta.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premier Publishing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thanhhaterracotta.com\/#website\",\"url\":\"https:\/\/thanhhaterracotta.com\/\",\"name\":\"C\u00f4ng vi\u00ean - B\u1ea3o t\u00e0ng \u0110\u1ea5t nung Thanh H\u00e0\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thanhhaterracotta.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Premier Publishing Archives - C\u00f4ng vi\u00ean - B\u1ea3o t\u00e0ng \u0110\u1ea5t nung Thanh H\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thanhhaterracotta.com\/en\/magazine-publisher\/premier-publishing\/","og_locale":"en_US","og_type":"article","og_title":"Premier Publishing Archives","og_url":"https:\/\/thanhhaterracotta.com\/en\/magazine-publisher\/premier-publishing\/","og_site_name":"C\u00f4ng vi\u00ean - B\u1ea3o t\u00e0ng \u0110\u1ea5t nung Thanh H\u00e0","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thanhhaterracotta.com\/magazine-publisher\/premier-publishing\/","url":"https:\/\/thanhhaterracotta.com\/magazine-publisher\/premier-publishing\/","name":"Premier Publishing Archives - C\u00f4ng vi\u00ean - B\u1ea3o t\u00e0ng \u0110\u1ea5t nung Thanh H\u00e0","isPartOf":{"@id":"https:\/\/thanhhaterracotta.com\/#website"},"breadcrumb":{"@id":"https:\/\/thanhhaterracotta.com\/magazine-publisher\/premier-publishing\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thanhhaterracotta.com\/magazine-publisher\/premier-publishing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Trang ch\u1ee7","item":"https:\/\/thanhhaterracotta.com\/"},{"@type":"ListItem","position":2,"name":"Premier Publishing"}]},{"@type":"WebSite","@id":"https:\/\/thanhhaterracotta.com\/#website","url":"https:\/\/thanhhaterracotta.com\/","name":"C\u00f4ng vi\u00ean - B\u1ea3o t\u00e0ng \u0110\u1ea5t nung Thanh H\u00e0","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thanhhaterracotta.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/thanhhaterracotta.com\/en\/wp-json\/wp\/v2\/magazine-publisher\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thanhhaterracotta.com\/en\/wp-json\/wp\/v2\/magazine-publisher"}],"about":[{"href":"https:\/\/thanhhaterracotta.com\/en\/wp-json\/wp\/v2\/taxonomies\/magazine-publisher"}],"wp:post_type":[{"href":"https:\/\/thanhhaterracotta.com\/en\/wp-json\/wp\/v2\/magazine?magazine-publisher=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}